{"id":2301,"date":"2008-04-01T00:20:03","date_gmt":"2008-03-31T22:20:03","guid":{"rendered":"http:\/\/www.carballada.com\/2008\/03\/shoot-em-up"},"modified":"2008-04-01T00:40:23","modified_gmt":"2008-03-31T22:40:23","slug":"shoot-em-up","status":"publish","type":"post","link":"https:\/\/www.carballada.com\/wordpress\/2008\/04\/shoot-em-up","title":{"rendered":"Shoot &#8216;Em Up"},"content":{"rendered":"<p><a href=\"http:\/\/www.carballada.com\/wp-content\/uploads\/shoot-em-up-1.jpg\" title=\"Shoot Em Up car\u00e1tula\"><img src=\"http:\/\/www.carballada.com\/wp-content\/uploads\/shoot-em-up-1.thumbnail.jpg\" alt=\"Shoot Em Up car\u00e1tula\" class=\"left\" \/><\/a><\/p>\n<p><strong>Puaggg<\/strong>.<\/p>\n<p>Otro fiasco para sumar al <em>cutrer\u00edo<\/em>.<\/p>\n<p>Creo que intenta ser <em>moderna<\/em>, <em>comiquera<\/em>, pero en mi opini\u00f3n se queda en un <strong>asquito <\/strong>de pel\u00edcula.<\/p>\n<p><strong>Buena <\/strong>banda sonora, m\u00fasica <em>dura <\/em>que da un buen ritmo a las <em>tonter\u00edas <\/em>que nos ense\u00f1an.<\/p>\n<p>Toda la pel\u00edcula est\u00e1 llena de <em>fantasmadas <\/em>sin gracia ni acierto y encima hay que aguantar tambi\u00e9n un humor de los mas <strong>tonto<\/strong>.<\/p>\n<p>Si quieres ver algo <em>facil\u00f3n<\/em>, que puedas comentar y olvidar al poco rato, te servir\u00e1.<\/p>\n<p>Muy mal, y es que hay otras muchas pel\u00edculas <strong>facilonas <\/strong>y <em>fren\u00e9ticas <\/em>del mismo estilo que consiguen no <strong>cabrearme <\/strong>tanto cuando las veo.<\/p>\n<p><!--more-->El protagonista es <a href=\"http:\/\/www.imdb.com\/name\/nm0654110\/\">Clive Owen<\/a>, m\u00e1s <em>caracart\u00f3n <\/em>de lo acostumbrado y ella es <a href=\"http:\/\/www.imdb.com\/name\/nm0000899\/\">Monica Bellucci<\/a> m\u00e1s <strong>abundante <\/strong>que nunca.<\/p>\n<p>El malo es un p\u00e9simo <a href=\"http:\/\/www.imdb.com\/name\/nm0316079\/\">Paul Giamatti<\/a>, \u00bfdonde est\u00e1 el <a href=\"http:\/\/www.imdb.com\/name\/nm0316079\/\">Paul Giamatti<\/a> de la m\u00e1gica <a href=\"http:\/\/www.imdb.com\/title\/tt0375063\/\">Sideways<\/a>?<\/p>\n<p>Se queda con un<\/p>\n<p><strong>Rating:<\/strong> <img src=\"http:\/\/www.carballada.com\/wordpress\/wp-content\/plugins\/star-rating-for-reviews\/images\/star.png\" alt=\"&#9733;\" \/><img src=\"http:\/\/www.carballada.com\/wordpress\/wp-content\/plugins\/star-rating-for-reviews\/images\/blankstar.png\" alt=\"&#9734;\" \/><img src=\"http:\/\/www.carballada.com\/wordpress\/wp-content\/plugins\/star-rating-for-reviews\/images\/blankstar.png\" alt=\"&#9734;\" \/><img src=\"http:\/\/www.carballada.com\/wordpress\/wp-content\/plugins\/star-rating-for-reviews\/images\/blankstar.png\" alt=\"&#9734;\" \/><img src=\"http:\/\/www.carballada.com\/wordpress\/wp-content\/plugins\/star-rating-for-reviews\/images\/blankstar.png\" alt=\"&#9734;\" \/><\/p>\n<p>Dejo el acceso a un <strong>elink <\/strong>perfecto en calidad <strong>dvdrip <\/strong>y sonido <em>AC3 5.1 <\/em>de la gente de<strong> legioequestris.com<\/strong><\/p>\n<p><a href=\"http:\/\/www.carballada.com\/disclaimer?elink=|file|Shoot.Em.Up.(En.el.Punto.de.Mira).-.XviD.DVDRip.(720x320).-.AC3.5.1.(ESP).-.QLT.(legioequestris.com).avi|1260206080|B5041C0C1235C6B5C61FCEBB8E5E7CCF|h=Z6F5MEPTSCAJCSYDU2BX2E5NKBM6Q4SJ|\/\">Shoot.Em.Up.(En.el.Punto.de.Mira).-.XviD.DVDRip.(720&#215;320).-.AC3.5.1.(ESP)<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Puaggg. Otro fiasco para sumar al cutrer\u00edo. Creo que intenta ser moderna, comiquera, pero en mi opini\u00f3n se queda en un asquito de pel\u00edcula. Buena banda sonora, m\u00fasica dura que da un buen ritmo a las tonter\u00edas que nos ense\u00f1an. Toda la pel\u00edcula est\u00e1 llena de fantasmadas sin gracia ni acierto y encima hay que [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[41],"tags":[61,96,79,54,230],"geo":null,"_links":{"self":[{"href":"https:\/\/www.carballada.com\/wordpress\/wp-json\/wp\/v2\/posts\/2301"}],"collection":[{"href":"https:\/\/www.carballada.com\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.carballada.com\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.carballada.com\/wordpress\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.carballada.com\/wordpress\/wp-json\/wp\/v2\/comments?post=2301"}],"version-history":[{"count":0,"href":"https:\/\/www.carballada.com\/wordpress\/wp-json\/wp\/v2\/posts\/2301\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.carballada.com\/wordpress\/wp-json\/wp\/v2\/media?parent=2301"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.carballada.com\/wordpress\/wp-json\/wp\/v2\/categories?post=2301"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.carballada.com\/wordpress\/wp-json\/wp\/v2\/tags?post=2301"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}