{"id":4583,"date":"2009-01-25T01:00:02","date_gmt":"2009-01-25T00:00:02","guid":{"rendered":"http:\/\/www.carballada.com\/2009\/01\/delicious-95"},"modified":"2009-01-25T19:12:05","modified_gmt":"2009-01-25T18:12:05","slug":"delicious-95","status":"publish","type":"post","link":"https:\/\/www.carballada.com\/wordpress\/2009\/01\/delicious-95","title":{"rendered":"Blogs 09\/04"},"content":{"rendered":"<p><img class=\"alignleft\" src=\"http:\/\/www.carballada.com\/wp-content\/uploads\/blogs.thumbnail.jpg\" alt=\"Blogs\" \/><\/p>\n<p>Aqu\u00ed est\u00e1n los \u00faltimos <strong>post<\/strong> que he visto que han despertado mi <em>inter\u00e9s<\/em> en la semana <strong>04<\/strong> del <strong>2009<\/strong>.<\/p>\n<p>As\u00ed puedes dar un paseo por los <strong>links<\/strong> que yo he estado mirando estos d\u00edas.<\/p>\n<p>Cada semana tienes un <strong>art\u00edculo<\/strong> con aquellos lugares o noticias de la red que encuentro m\u00e1s <em>interesantes<\/em>, estos <strong>art\u00edculos<\/strong> siempre los encontrar\u00e1s en la categor\u00eda <a title=\"categor\u00eda Blogs\" href=\"http:\/\/www.carballada.com\/category\/opinion\/blogs\/\">Blogs<\/a>.<\/p>\n<p><!--more--><\/p>\n<p>Esta es la lista de los de <strong>esta <\/strong>semana:<\/p>\n<ul>\n<li><a title=\"http:\/\/www.drpez.net\/panel\/showthread.php?t=152748\" href=\"http:\/\/www.drpez.net\/panel\/showthread.php?t=152748\">RDSB, camas de arena remotas (o DSB en un bidon)<\/a><br \/>\nhablando sobre esta idea<\/li>\n<li><a title=\"http:\/\/www.compradiccion.com\/2009\/01\/22-patatas-fritas-con-chocolate\" href=\"http:\/\/www.compradiccion.com\/2009\/01\/22-patatas-fritas-con-chocolate\">Patatas fritas con chocolate<\/a><br \/>\nhay que probarlas<\/li>\n<li><a title=\"http:\/\/www.ojobuscador.com\/2009\/01\/21\/google-earth-geoeye-1-y-barack-obama\/\" href=\"http:\/\/www.ojobuscador.com\/2009\/01\/21\/google-earth-geoeye-1-y-barack-obama\/\">Google Earth, GeoEye-1 y Barack Obama<\/a><br \/>\nuna cosilla mas<\/li>\n<li><a title=\"http:\/\/crackberry.com\/os-4-7-0-90-leaked-blackberry-storm-9530-9500\" href=\"http:\/\/crackberry.com\/os-4-7-0-90-leaked-blackberry-storm-9530-9500\">Best Yet: OS 4.7.0.90 Leaked for the Storm 9530 &amp; 9500!<\/a><br \/>\npues vamos a probarla ya, que tal y como est\u00e1 no estoy utiliz\u00e1ndola por ir fatal<\/li>\n<li><a title=\"http:\/\/www.ungatonipon.com\/?p=1178\" href=\"http:\/\/www.ungatonipon.com\/?p=1178\">Hilarantes Consejos de Seguridad para japoneses en UnGatoNip\u00f3n<\/a><br \/>\nque gracia<\/li>\n<li><a title=\"http:\/\/cuatrotipos.wordpress.com\/2009\/01\/18\/fairey-shepard-obama-obedece-al-gigante\/\" href=\"http:\/\/cuatrotipos.wordpress.com\/2009\/01\/18\/fairey-shepard-obama-obedece-al-gigante\/\">Shepard Fairey, Obama, Obedece al Gigante<\/a><br \/>\nhablando de Fairey<\/li>\n<li><a title=\"http:\/\/www.clipset.net\/2009\/01\/19\/anuncios-reales-hackeados-con-photoshop\/\" href=\"http:\/\/www.clipset.net\/2009\/01\/19\/anuncios-reales-hackeados-con-photoshop\/\">Anuncios hackeados<\/a><br \/>\nme gusta la idea<\/li>\n<li><a title=\"http:\/\/www.xataka.com\/2009\/01\/20-formatos-panoramicos-a-fondo-i\" href=\"http:\/\/www.xataka.com\/2009\/01\/20-formatos-panoramicos-a-fondo-i\">Formatos panor\u00e1micos: a fondo (I)<\/a><br \/>\nbuena explicaci\u00f3n<\/li>\n<li><a title=\"http:\/\/www.20minutos.es\/noticia\/444850\/0\/atar\/cables\/arboles\/\" href=\"http:\/\/www.20minutos.es\/noticia\/444850\/0\/atar\/cables\/arboles\/\">Detenido por colocar trampas contra motoristas y ciclistas en caminos rurales &#8211; 20minutos.es<\/a><br \/>\nde entrada y sin dudarlo: la puta madre que lo pari\u00f3 al asesino de mierda<\/li>\n<li><a title=\"http:\/\/www.copyscape.com\/\" href=\"http:\/\/www.copyscape.com\/\">Copyscape &#8211; Search for Website Plagiarism and Duplicate Content Online<\/a><br \/>\npara comprobar si te est\u00e1n copiando<\/li>\n<li><a title=\"http:\/\/unahijadeputaconclase.blogspot.com\/2009\/01\/que-os-den-por-el-culo.html\" href=\"http:\/\/unahijadeputaconclase.blogspot.com\/2009\/01\/que-os-den-por-el-culo.html\">Que os den por el culo<\/a><br \/>\npensamientos de Una hija de puta con clase<\/li>\n<li><a title=\"http:\/\/www.lavanguardia.es\/ciudadanos\/noticias\/20081128\/53588629575\/motoadictos-barcelona-madrid-roma-ap.html\" href=\"http:\/\/www.lavanguardia.es\/ciudadanos\/noticias\/20081128\/53588629575\/motoadictos-barcelona-madrid-roma-ap.html\">Motoadictos<\/a><br \/>\nHablemos en serio sobre el uso de la moto en la ciudad<\/li>\n<li><a title=\"http:\/\/tineye.com\/login\" href=\"http:\/\/tineye.com\/login\">TinEye Reverse Image Search<\/a><br \/>\nbuscador de tus propias fotos<\/li>\n<li><a title=\"http:\/\/www.kirainet.com\/kawaii\/\" href=\"http:\/\/www.kirainet.com\/kawaii\/\">Kawaii<\/a><br \/>\naclar\u00e1ndome sobre qu\u00e9 es kawaii<\/li>\n<li><a title=\"http:\/\/www.coralreefecosystems.com\/ltg_bulb_color.htm\" href=\"http:\/\/www.coralreefecosystems.com\/ltg_bulb_color.htm\">Bulb Color Comparisons<\/a><br \/>\ncomparaci\u00f3n de los efectos de la luz cambiando la temperatura de color de las l\u00e1mparas<\/li>\n<li><a title=\"http:\/\/noonemexico.blogspot.com\/2008\/03\/y-que-se-me-cae-un-scwd.html\" href=\"http:\/\/noonemexico.blogspot.com\/2008\/03\/y-que-se-me-cae-un-scwd.html\">Y que se me cae un SCWD<\/a><br \/>\nmodificaciones a un generador de olas SCWD para poder quitarlo y limpiarlo<\/li>\n<li><a title=\"http:\/\/www.naclu2.com\/index.php?option=com_content&amp;view=article&amp;id=11:aquascaping&amp;catid=4:numero-2\" href=\"http:\/\/www.naclu2.com\/index.php?option=com_content&amp;view=article&amp;id=11:aquascaping&amp;catid=4:numero-2\">Aquascaping<\/a><br \/>\nhablando de t\u00e9cnicas de decoraci\u00f3n en acuarios marinos<\/li>\n<li><a title=\"http:\/\/services.google.com\/enterprise\/enterprise_form\" href=\"http:\/\/services.google.com\/enterprise\/enterprise_form\">Enterprise Help Center<\/a><br \/>\nla p\u00e1gina de Google para el GSA<\/li>\n<li><a title=\"http:\/\/www.filmica.com\/david_bravo\/archivos\/008918.html\" href=\"http:\/\/www.filmica.com\/david_bravo\/archivos\/008918.html\">David Bravo &#8211; Revientan y ridiculizan la campa\u00f1a \u00abSi eres legal, eres legal\u00bb<\/a><br \/>\nsi es que mucha ignorancia nunca es poca<\/li>\n<li><a title=\"http:\/\/www.publico.es\/ciencias\/192216\/sgae\/presenta\/primer\/disco\/formato\/web\" href=\"http:\/\/www.publico.es\/ciencias\/192216\/sgae\/presenta\/primer\/disco\/formato\/web\">La SGAE descubre (ahora) el negocio de la m\u00fasica online<\/a><br \/>\nvaya tela<\/li>\n<li><a title=\"http:\/\/www.bajandoalbums.com\/\" href=\"http:\/\/www.bajandoalbums.com\/\">Bajando Albums . com<\/a><br \/>\ntoda la m\u00fasica que va apareciendo<\/li>\n<li><a title=\"http:\/\/www.taboagua.net\/\" href=\"http:\/\/www.taboagua.net\/\">Taboagua<\/a><br \/>\nventa equipos osmosis inversa descacificadores filtros agua<\/li>\n<li><a title=\"http:\/\/www.acquaportal.it\/Faidate\/\" href=\"http:\/\/www.acquaportal.it\/Faidate\/\">Acquari Fai da te &#8211; AcquaPortal &#8211;<\/a><br \/>\nmontones y montones de DIY para el acuario<\/li>\n<li><a title=\"http:\/\/ozreef.org\/index.php?set_albumName=diy&amp;option=com_gallery&amp;Itemid=46&amp;include=view_album.php&amp;page=10\" href=\"http:\/\/ozreef.org\/index.php?set_albumName=diy&amp;option=com_gallery&amp;Itemid=46&amp;include=view_album.php&amp;page=10\">OZ REEF<\/a><br \/>\nsoluciones DIY para acuarios<\/li>\n<li><a title=\"http:\/\/www.aquaristsonline.com\/blog\/aquarium-diy\/aquarium-diy-have-fun-and-save-some-money\/\" href=\"http:\/\/www.aquaristsonline.com\/blog\/aquarium-diy\/aquarium-diy-have-fun-and-save-some-money\/\">Aquarium DIY &#8211; Have Fun And Save Some Money<\/a><br \/>\nproyectos DIY para acuarios<\/li>\n<li><a title=\"http:\/\/www.fish-street.com\/index.php\" href=\"http:\/\/www.fish-street.com\/index.php\">Fish Street Store<\/a><br \/>\ntodos los productos chinos para acuarios marinos<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Aqu\u00ed est\u00e1n los \u00faltimos post que he visto que han despertado mi inter\u00e9s en la semana 04 del 2009. As\u00ed puedes dar un paseo por los links que yo he estado mirando estos d\u00edas. Cada semana tienes un art\u00edculo con aquellos lugares o noticias de la red que encuentro m\u00e1s interesantes, estos art\u00edculos siempre los [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[22],"tags":[243],"geo":null,"_links":{"self":[{"href":"https:\/\/www.carballada.com\/wordpress\/wp-json\/wp\/v2\/posts\/4583"}],"collection":[{"href":"https:\/\/www.carballada.com\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.carballada.com\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.carballada.com\/wordpress\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.carballada.com\/wordpress\/wp-json\/wp\/v2\/comments?post=4583"}],"version-history":[{"count":0,"href":"https:\/\/www.carballada.com\/wordpress\/wp-json\/wp\/v2\/posts\/4583\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.carballada.com\/wordpress\/wp-json\/wp\/v2\/media?parent=4583"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.carballada.com\/wordpress\/wp-json\/wp\/v2\/categories?post=4583"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.carballada.com\/wordpress\/wp-json\/wp\/v2\/tags?post=4583"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}