{"id":73,"date":"2006-06-06T22:00:20","date_gmt":"2006-06-06T21:00:20","guid":{"rendered":"http:\/\/www.carballada.com\/?p=73"},"modified":"2006-07-21T21:58:22","modified_gmt":"2006-07-21T20:58:22","slug":"la-cosecha-de-hielo","status":"publish","type":"post","link":"https:\/\/www.carballada.com\/wordpress\/2006\/06\/la-cosecha-de-hielo","title":{"rendered":"La cosecha de hielo"},"content":{"rendered":"<p><a title=\"La cosecha de hielo\" class=\"imagelink\" href=\"http:\/\/www.carballada.com\/wp-content\/uploads\/lac.jpg\"><img loading=\"lazy\" width=\"250\" height=\"362\" alt=\"La cosecha de hielo\" id=\"image72\" src=\"http:\/\/www.carballada.com\/wp-content\/uploads\/lac.jpg\" \/><\/a><\/p>\n<p><a target=\"_blank\" title=\"La cosecha de hielo\" href=\"http:\/\/www.carballada.com\/disclaimer?elink=|file|La.Cosecha.De.Hielo.DVD-Rip.Xvid-Ac3.Spanish.www.MorciDivx.com.avi|734103552|85BD9359859170D6E8F79929B48E3A2B|\/\">http:\/\/www.carballada.com\/disclaimer?elink=|file|La.Cosecha.De.Hielo.DVD-Rip.Xvid-Ac3.Spanish&#8230;<\/a><\/p>\n<p>(es un elink a una copia bastante buena para su tama\u00f1o, en AC3)<\/p>\n<p>Me ha gustado mucho.<\/p>\n<p>El Cusack esta muy bien, me encanta en esos papeles de perdedor despistado, con cara de ni\u00f1o bueno.<\/p>\n<p>Tiene una suerte increible, eso si.<\/p>\n<p>Es como una peli de polis y ladrones, pero sin polis, no se, jajaja, es para verla, esta bien.<\/p>\n<p>La mujer fatal, demasiado fatal, demasiado artificial, pero bueno.<\/p>\n<p>Guion muy bueno, hay que estar atento a los nombres de los personajes para no perderse.<\/p>\n<p>Le pondr\u00e9 un <strong>Rating:<\/strong> <img src=\"http:\/\/www.carballada.com\/wordpress\/wp-content\/plugins\/star-rating-for-reviews\/images\/star.png\" alt=\"&#9733;\" \/><img src=\"http:\/\/www.carballada.com\/wordpress\/wp-content\/plugins\/star-rating-for-reviews\/images\/star.png\" alt=\"&#9733;\" \/><img src=\"http:\/\/www.carballada.com\/wordpress\/wp-content\/plugins\/star-rating-for-reviews\/images\/star.png\" alt=\"&#9733;\" \/><img src=\"http:\/\/www.carballada.com\/wordpress\/wp-content\/plugins\/star-rating-for-reviews\/images\/halfstar.png\" alt=\"&frac12;\" \/><img src=\"http:\/\/www.carballada.com\/wordpress\/wp-content\/plugins\/star-rating-for-reviews\/images\/blankstar.png\" alt=\"&#9734;\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>http:\/\/www.carballada.com\/disclaimer?elink=|file|La.Cosecha.De.Hielo.DVD-Rip.Xvid-Ac3.Spanish&#8230; (es un elink a una copia bastante buena para su tama\u00f1o, en AC3) Me ha gustado mucho. El Cusack esta muy bien, me encanta en esos papeles de perdedor despistado, con cara de ni\u00f1o bueno. Tiene una suerte increible, eso si. Es como una peli de polis y ladrones, pero sin polis, no se, [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[41],"tags":[96,79,54,57,230],"geo":null,"_links":{"self":[{"href":"https:\/\/www.carballada.com\/wordpress\/wp-json\/wp\/v2\/posts\/73"}],"collection":[{"href":"https:\/\/www.carballada.com\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.carballada.com\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.carballada.com\/wordpress\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.carballada.com\/wordpress\/wp-json\/wp\/v2\/comments?post=73"}],"version-history":[{"count":0,"href":"https:\/\/www.carballada.com\/wordpress\/wp-json\/wp\/v2\/posts\/73\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.carballada.com\/wordpress\/wp-json\/wp\/v2\/media?parent=73"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.carballada.com\/wordpress\/wp-json\/wp\/v2\/categories?post=73"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.carballada.com\/wordpress\/wp-json\/wp\/v2\/tags?post=73"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}