{"id":8705,"date":"2013-02-27T22:15:36","date_gmt":"2013-02-27T20:15:36","guid":{"rendered":"http:\/\/www.carballada.com\/?p=8705"},"modified":"2013-02-27T22:16:05","modified_gmt":"2013-02-27T20:16:05","slug":"monstruoso-cloverfield","status":"publish","type":"post","link":"https:\/\/www.carballada.com\/wordpress\/2013\/02\/monstruoso-cloverfield","title":{"rendered":"Monstruoso (Cloverfield)"},"content":{"rendered":"<p><a href=\"http:\/\/www.carballada.com\/wp-content\/uploads\/Cloverfield_poster.jpg\"><img loading=\"lazy\" class=\"alignleft size-thumbnail wp-image-8783\" alt=\"Cloverfield_poster\" src=\"http:\/\/www.carballada.com\/wp-content\/uploads\/Cloverfield_poster-85x128.jpg\" width=\"85\" height=\"128\" srcset=\"https:\/\/www.carballada.com\/wordpress\/wp-content\/uploads\/Cloverfield_poster-85x128.jpg 85w, https:\/\/www.carballada.com\/wordpress\/wp-content\/uploads\/Cloverfield_poster-200x300.jpg 200w, https:\/\/www.carballada.com\/wordpress\/wp-content\/uploads\/Cloverfield_poster-684x1024.jpg 684w, https:\/\/www.carballada.com\/wordpress\/wp-content\/uploads\/Cloverfield_poster.jpg 1100w\" sizes=\"(max-width: 85px) 100vw, 85px\" \/><\/a>He <em>tardado<\/em> en verla, es del 2008, pero es que siempre se me antoj\u00f3 una pel\u00edcula <strong>floja<\/strong> y <em>sencilla<\/em> sobre un tema ya <em>demasiado<\/em> visto.<\/p>\n<p>Y ha estado <strong>bien<\/strong>, ha sido <em>mucho<\/em> mejor de lo que me esperaba, todo empez\u00f3 al ver un peque\u00f1o <em>fragmento,<\/em>\u00a0me enganch\u00f3.<\/p>\n<p>Utiliza un formato muy <em>particular<\/em> ya empleado en otras <strong>pel\u00edculas<\/strong> como en su momento ya lo hizo\u00a0<b><a href=\"http:\/\/www.imdb.com\/title\/tt0185937\/\">El projecto de la bruja de Blair<\/a>.<\/b><\/p>\n<p>Todo tiene un aire de <strong>grabaci\u00f3n<\/strong> casual, con <em>c\u00e1mara<\/em> en mano y eso aumenta la tensi\u00f3n de una manera <em>considerable<\/em>.<\/p>\n<p>En <strong>Mostruoso<\/strong> lo que hay\u00a0tambi\u00e9n\u00a0son <em>muchos<\/em> efectos especiales, <em>muchos<\/em>, pero muchos muchos. Creo que hasta se les ha ido un poco la <em>cabeza<\/em> con tanta maravilla.<\/p>\n<p>Se nota la mano de\u00a0<a href=\"http:\/\/www.imdb.com\/name\/nm0009190\/\">J.J. Abrams<\/a>\u00a0como <strong>productor<\/strong>.<\/p>\n<p><!--more-->El <em>director<\/em> es\u00a0<a href=\"http:\/\/www.imdb.com\/name\/nm0716257\/?ref_=tt_ov_dr\">Matt Reeves<\/a>, no muy conocido pero participante como <em>guionista<\/em> y <em>director<\/em>\u00a0en varias series de televisi\u00f3n, imagino que ser\u00e1 bastante <em>aminiguino<\/em> de\u00a0<a href=\"http:\/\/www.imdb.com\/name\/nm0009190\/\">J.J. Abrams<\/a>.<\/p>\n<p>Los <strong>actores<\/strong> protagonistas\u00a0no son muy conocidos, quiz\u00e1s\u00a0<a href=\"http:\/\/www.imdb.com\/name\/nm0951148\/?ref_=tt_cl_t6\">Odette Annable<\/a>\u00a0es la que mas me suena.<\/p>\n<p>La pel\u00edcula se lleva un<\/p>\n<p><strong>Rating:<\/strong> <img src=\"http:\/\/www.carballada.com\/wordpress\/wp-content\/plugins\/star-rating-for-reviews\/images\/star.png\" alt=\"&#9733;\" \/><img src=\"http:\/\/www.carballada.com\/wordpress\/wp-content\/plugins\/star-rating-for-reviews\/images\/star.png\" alt=\"&#9733;\" \/><img src=\"http:\/\/www.carballada.com\/wordpress\/wp-content\/plugins\/star-rating-for-reviews\/images\/star.png\" alt=\"&#9733;\" \/><img src=\"http:\/\/www.carballada.com\/wordpress\/wp-content\/plugins\/star-rating-for-reviews\/images\/blankstar.png\" alt=\"&#9734;\" \/><img src=\"http:\/\/www.carballada.com\/wordpress\/wp-content\/plugins\/star-rating-for-reviews\/images\/blankstar.png\" alt=\"&#9734;\" \/><\/p>\n<p>Dejo el <em>trailer<\/em> en castellano, aunque es una de esas pel\u00edculas que en <strong>V.O.<\/strong> mejora bastante<\/p>\n<span class=\"vvqbox vvqyoutube\" style=\"width:490px;height:300px;\"><span id=\"vvq-8705-youtube-1\"><a href=\"http:\/\/www.youtube.com\/watch?v=U8RI7eO1Y6Q\"><img src=\"http:\/\/img.youtube.com\/vi\/U8RI7eO1Y6Q\/0.jpg\" alt=\"Imagen de previsualizaci\u00f3n de YouTube\" \/><\/a><\/span><\/span>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>He tardado en verla, es del 2008, pero es que siempre se me antoj\u00f3 una pel\u00edcula floja y sencilla sobre un tema ya demasiado visto. Y ha estado bien, ha sido mucho mejor de lo que me esperaba, todo empez\u00f3 al ver un peque\u00f1o fragmento,\u00a0me enganch\u00f3. Utiliza un formato muy particular ya empleado en otras [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[42],"tags":[234,96,111,229,219],"geo":null,"_links":{"self":[{"href":"https:\/\/www.carballada.com\/wordpress\/wp-json\/wp\/v2\/posts\/8705"}],"collection":[{"href":"https:\/\/www.carballada.com\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.carballada.com\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.carballada.com\/wordpress\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.carballada.com\/wordpress\/wp-json\/wp\/v2\/comments?post=8705"}],"version-history":[{"count":9,"href":"https:\/\/www.carballada.com\/wordpress\/wp-json\/wp\/v2\/posts\/8705\/revisions"}],"predecessor-version":[{"id":8789,"href":"https:\/\/www.carballada.com\/wordpress\/wp-json\/wp\/v2\/posts\/8705\/revisions\/8789"}],"wp:attachment":[{"href":"https:\/\/www.carballada.com\/wordpress\/wp-json\/wp\/v2\/media?parent=8705"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.carballada.com\/wordpress\/wp-json\/wp\/v2\/categories?post=8705"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.carballada.com\/wordpress\/wp-json\/wp\/v2\/tags?post=8705"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}