{"id":8805,"date":"2013-05-16T22:23:04","date_gmt":"2013-05-16T20:23:04","guid":{"rendered":"http:\/\/www.carballada.com\/?p=8805"},"modified":"2013-05-17T09:23:44","modified_gmt":"2013-05-17T07:23:44","slug":"el-fraude","status":"publish","type":"post","link":"https:\/\/www.carballada.com\/wordpress\/2013\/05\/el-fraude","title":{"rendered":"El Fraude"},"content":{"rendered":"<p><a href=\"http:\/\/www.carballada.com\/wp-content\/uploads\/el-fraude.jpg\"><img loading=\"lazy\" class=\"alignleft size-thumbnail wp-image-8874\" alt=\"el fraude\" src=\"http:\/\/www.carballada.com\/wp-content\/uploads\/el-fraude-86x128.jpg\" width=\"86\" height=\"128\" srcset=\"https:\/\/www.carballada.com\/wordpress\/wp-content\/uploads\/el-fraude-86x128.jpg 86w, https:\/\/www.carballada.com\/wordpress\/wp-content\/uploads\/el-fraude-202x300.jpg 202w, https:\/\/www.carballada.com\/wordpress\/wp-content\/uploads\/el-fraude.jpg 509w\" sizes=\"(max-width: 86px) 100vw, 86px\" \/><\/a>Sin pena ni gloria.<\/p>\n<p>Creo que el <em>problema<\/em> que he tenido con esta pel\u00edcula es que me ha resultado del todo <strong>previsible<\/strong>.<\/p>\n<p>Es un <em>tema<\/em> ya tan tratado, tan <em>usado<\/em>, tan repetido que cuesta sorprender con algo nuevo.<\/p>\n<p>Aunque pens\u00e1ndolo un poco, creo que <strong>no<\/strong> han querido sorprender, <em>simplemente<\/em>\u00a0han querido ofrecer un producto de <strong>consumo<\/strong>, t\u00edpico.<\/p>\n<p>Para que sea un buen <em>producto<\/em> simplemente le han a\u00f1adido unas cuantas caras conocidas, lo han empaquetado como siempre lo hacen y listo: ya tienes tu <em>peli<\/em> de pasar el rato.<\/p>\n<p>El <em>protagonista<\/em> es un\u00a0<a itemprop=\"url\" href=\"http:\/\/www.imdb.com\/name\/nm0000152\/?ref_=tt_cl_t1\">Richard Gere<\/a>\u00a0correcto, sin demasiada <em>guapura<\/em> o demasiados encantos, est\u00e1 bien.<\/p>\n<p><!--more-->Ella es\u00a0<a itemprop=\"url\" href=\"http:\/\/www.imdb.com\/name\/nm0000215\/?ref_=tt_cl_t2\">Susan Sarandon<\/a>, sus <strong>interpretaciones<\/strong> siempre me gustan.<\/p>\n<p>Tambi\u00e9n tenemos a un desperdiciado\u00a0<a itemprop=\"url\" href=\"http:\/\/www.imdb.com\/name\/nm0000619\/?ref_=tt_cl_t3\">Tim Roth<\/a>, caricatura de el mismo, cada vez peor.<\/p>\n<p>Y la guapa que no pod\u00eda faltar es\u00a0<a itemprop=\"url\" href=\"http:\/\/www.imdb.com\/name\/nm0144377\/?ref_=tt_cl_t5\">Laetitia Casta<\/a>, sin comentarios.<\/p>\n<p>El <em>director<\/em> y <em>guionista<\/em> es el novel <a itemprop=\"url\" href=\"http:\/\/www.imdb.com\/name\/nm1906430\/?ref_=tt_ov_dr\">Nicholas Jarecki<\/a>, tiene alg\u00fan corto y poca cosa m\u00e1s.<\/p>\n<p>La pel\u00edcula se lleva un<\/p>\n<p><strong>Rating:<\/strong> <img src=\"http:\/\/www.carballada.com\/wordpress\/wp-content\/plugins\/star-rating-for-reviews\/images\/star.png\" alt=\"&#9733;\" \/><img src=\"http:\/\/www.carballada.com\/wordpress\/wp-content\/plugins\/star-rating-for-reviews\/images\/star.png\" alt=\"&#9733;\" \/><img src=\"http:\/\/www.carballada.com\/wordpress\/wp-content\/plugins\/star-rating-for-reviews\/images\/halfstar.png\" alt=\"&frac12;\" \/><img src=\"http:\/\/www.carballada.com\/wordpress\/wp-content\/plugins\/star-rating-for-reviews\/images\/blankstar.png\" alt=\"&#9734;\" \/><img src=\"http:\/\/www.carballada.com\/wordpress\/wp-content\/plugins\/star-rating-for-reviews\/images\/blankstar.png\" alt=\"&#9734;\" \/><\/p>\n<p>Entretenida, pero nada m\u00e1s, incluso <strong>aburrida<\/strong> si tienes un mal d\u00eda. Pero se puede ver sin problemas.<\/p>\n<p>Os dejo un trailer fant\u00e1stico.<\/p>\n<span class=\"vvqbox vvqyoutube\" style=\"width:490px;height:300px;\"><span id=\"vvq-8805-youtube-1\"><a href=\"http:\/\/www.youtube.com\/watch?v=qawyuFVVK-s\"><img src=\"http:\/\/img.youtube.com\/vi\/qawyuFVVK-s\/0.jpg\" alt=\"Imagen de previsualizaci\u00f3n de YouTube\" \/><\/a><\/span><\/span>\n","protected":false},"excerpt":{"rendered":"<p>Sin pena ni gloria. Creo que el problema que he tenido con esta pel\u00edcula es que me ha resultado del todo previsible. Es un tema ya tan tratado, tan usado, tan repetido que cuesta sorprender con algo nuevo. Aunque pens\u00e1ndolo un poco, creo que no han querido sorprender, simplemente\u00a0han querido ofrecer un producto de consumo, [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[44],"tags":[234,96,111,229,219],"geo":null,"_links":{"self":[{"href":"https:\/\/www.carballada.com\/wordpress\/wp-json\/wp\/v2\/posts\/8805"}],"collection":[{"href":"https:\/\/www.carballada.com\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.carballada.com\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.carballada.com\/wordpress\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.carballada.com\/wordpress\/wp-json\/wp\/v2\/comments?post=8805"}],"version-history":[{"count":3,"href":"https:\/\/www.carballada.com\/wordpress\/wp-json\/wp\/v2\/posts\/8805\/revisions"}],"predecessor-version":[{"id":8877,"href":"https:\/\/www.carballada.com\/wordpress\/wp-json\/wp\/v2\/posts\/8805\/revisions\/8877"}],"wp:attachment":[{"href":"https:\/\/www.carballada.com\/wordpress\/wp-json\/wp\/v2\/media?parent=8805"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.carballada.com\/wordpress\/wp-json\/wp\/v2\/categories?post=8805"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.carballada.com\/wordpress\/wp-json\/wp\/v2\/tags?post=8805"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}